{"id":14158,"date":"2017-02-10T17:21:10","date_gmt":"2017-02-10T16:21:10","guid":{"rendered":"http:\/\/www.botteroskiblog.com\/?p=14158"},"modified":"2020-04-21T11:42:43","modified_gmt":"2020-04-21T09:42:43","slug":"ciaspo-polenta-unisciti-a-noi-la-sera-del-18-febbraio","status":"publish","type":"post","link":"https:\/\/www.botteroski.com\/blog\/2017\/02\/10\/ciaspo-polenta-unisciti-a-noi-la-sera-del-18-febbraio\/","title":{"rendered":"Ciaspo-Polenta: unisciti a noi la sera del 18 febbraio"},"content":{"rendered":"<p><img class=\"aligncenter wp-image-14162 size-full\" src=\"https:\/\/www.botteroski.com\/blog\/wp-content\/uploads\/2017\/02\/ciaspo-polenta-2107.jpg\" alt=\"ciaspo-polenta 2107\" width=\"1200\" height=\"1978\" srcset=\"https:\/\/www.botteroski.com\/blog\/wp-content\/uploads\/2017\/02\/ciaspo-polenta-2107.jpg 1200w, https:\/\/www.botteroski.com\/blog\/wp-content\/uploads\/2017\/02\/ciaspo-polenta-2107-182x300.jpg 182w, https:\/\/www.botteroski.com\/blog\/wp-content\/uploads\/2017\/02\/ciaspo-polenta-2107-621x1024.jpg 621w, https:\/\/www.botteroski.com\/blog\/wp-content\/uploads\/2017\/02\/ciaspo-polenta-2107-768x1266.jpg 768w, https:\/\/www.botteroski.com\/blog\/wp-content\/uploads\/2017\/02\/ciaspo-polenta-2107-932x1536.jpg 932w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>Appuntamento sabato 18 febbraio per la Ciaspo-Polenta, la serata ormai diventata un classico a Limone Piemonte\u2028: prima la cena a base di polenta presso l&#8217;Apr\u00e8s Ski Bottero Ski, e poi una ciaspolata notturna sulle suggestive Alpi piemontesi.<\/p>\n<p><strong>PROGRAMMA<br \/>\n<\/strong>ore 18,30: ritrovo presso il noleggio Botteroski<br \/>\nore 19,00 partenza dal noleggio Botteroski<\/p>\n<p>CENA CON POLENTA 20\u20ac*<br \/>\nCENA CON POLENTA + CIASPOLATA CON GUIDA ALPINA 25\u20ac*<br \/>\nCENA CON POLENTA + CIASPOLATA CON GUIDA ALPINA + NOLEGGIO CIASPOLE 30\u20ac*<br \/>\n<em>\u2028(* bevande escluse)<\/em><\/p>\n<p>Prenota entro gioved\u00ec 16 febbraio alle ore 19,30 al 329.2708075 oppure scrivendo a <a href=\"mailto:info@botteroski.com\">info@botteroski.com<\/a><\/p>\n<p><img class=\"aligncenter wp-image-14159 size-full\" src=\"https:\/\/www.botteroski.com\/blog\/wp-content\/uploads\/2017\/02\/16665039_1000886476712154_2917095904148359724_o.jpg\" alt=\"16665039_1000886476712154_2917095904148359724_o\" width=\"1200\" height=\"1200\" srcset=\"https:\/\/www.botteroski.com\/blog\/wp-content\/uploads\/2017\/02\/16665039_1000886476712154_2917095904148359724_o.jpg 1200w, https:\/\/www.botteroski.com\/blog\/wp-content\/uploads\/2017\/02\/16665039_1000886476712154_2917095904148359724_o-300x300.jpg 300w, https:\/\/www.botteroski.com\/blog\/wp-content\/uploads\/2017\/02\/16665039_1000886476712154_2917095904148359724_o-1024x1024.jpg 1024w, https:\/\/www.botteroski.com\/blog\/wp-content\/uploads\/2017\/02\/16665039_1000886476712154_2917095904148359724_o-150x150.jpg 150w, https:\/\/www.botteroski.com\/blog\/wp-content\/uploads\/2017\/02\/16665039_1000886476712154_2917095904148359724_o-768x768.jpg 768w, https:\/\/www.botteroski.com\/blog\/wp-content\/uploads\/2017\/02\/16665039_1000886476712154_2917095904148359724_o-100x100.jpg 100w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p><span style=\"border-radius: 2px; text-indent: 20px; width: auto; padding: 0px 4px 0px 0px; text-align: center; font: bold 11px\/20px 'Helvetica Neue',Helvetica,sans-serif; color: #ffffff; background: #bd081c no-repeat scroll 3px 50% \/ 14px 14px; position: absolute; opacity: 1; z-index: 8675309; display: none; cursor: pointer; top: 356px; left: 118px;\">Salva<\/span><\/p>\n<p><span style=\"border-radius: 2px; text-indent: 20px; width: auto; padding: 0px 4px 0px 0px; text-align: center; font: bold 11px\/20px 'Helvetica Neue',Helvetica,sans-serif; color: #ffffff; background: #bd081c  no-repeat scroll 3px 50% \/ 14px 14px; position: absolute; opacity: 1; z-index: 8675309; display: none; cursor: pointer; top: 36px; left: 118px;\">Salva<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Appuntamento sabato 18 febbraio per la Ciaspo-Polenta, la serata ormai diventata un classico a Limone Piemonte\u2028: prima la cena a base di polenta presso l&#8217;Apr\u00e8s Ski Bottero Ski, e poi una ciaspolata notturna sulle suggestive Alpi piemontesi. PROGRAMMA ore 18,30: ritrovo presso il noleggio Botteroski ore 19,00 partenza dal noleggio Botteroski CENA CON POLENTA 20\u20ac*&#8230;<\/p>\n","protected":false},"author":2,"featured_media":14162,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[159],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ciaspo-Polenta: unisciti a noi la sera del 18 febbraio - Bottero Ski Blog<\/title>\n<meta name=\"description\" content=\"Appuntamento sabato 18 febbraio per la Ciaspo-Polenta\u2028: cena a base di polenta presso l&#039;Apr\u00e8s Ski Bottero Ski e ciaspolata notturna.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.botteroski.com\/blog\/2017\/02\/10\/ciaspo-polenta-unisciti-a-noi-la-sera-del-18-febbraio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ciaspo-Polenta: unisciti a noi la sera del 18 febbraio - Bottero Ski Blog\" \/>\n<meta property=\"og:description\" content=\"Appuntamento sabato 18 febbraio per la Ciaspo-Polenta\u2028: cena a base di polenta presso l&#039;Apr\u00e8s Ski Bottero Ski e ciaspolata notturna.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.botteroski.com\/blog\/2017\/02\/10\/ciaspo-polenta-unisciti-a-noi-la-sera-del-18-febbraio\/\" \/>\n<meta property=\"og:site_name\" content=\"Bottero Ski Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/botteroski\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-10T16:21:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-21T09:42:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.botteroski.com\/blog\/wp-content\/uploads\/2017\/02\/ciaspo-polenta-2107.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1978\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.botteroski.com\/blog\/#website\",\"url\":\"https:\/\/www.botteroski.com\/blog\/\",\"name\":\"Bottero Ski Blog\",\"description\":\"News, curiosit\\u00e0 e consigli dal mondo Botteroski!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.botteroski.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.botteroski.com\/blog\/2017\/02\/10\/ciaspo-polenta-unisciti-a-noi-la-sera-del-18-febbraio\/#primaryimage\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/www.botteroski.com\/blog\/wp-content\/uploads\/2017\/02\/ciaspo-polenta-2107.jpg\",\"contentUrl\":\"https:\/\/www.botteroski.com\/blog\/wp-content\/uploads\/2017\/02\/ciaspo-polenta-2107.jpg\",\"width\":1200,\"height\":1978},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.botteroski.com\/blog\/2017\/02\/10\/ciaspo-polenta-unisciti-a-noi-la-sera-del-18-febbraio\/#webpage\",\"url\":\"https:\/\/www.botteroski.com\/blog\/2017\/02\/10\/ciaspo-polenta-unisciti-a-noi-la-sera-del-18-febbraio\/\",\"name\":\"Ciaspo-Polenta: unisciti a noi la sera del 18 febbraio - Bottero Ski Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.botteroski.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.botteroski.com\/blog\/2017\/02\/10\/ciaspo-polenta-unisciti-a-noi-la-sera-del-18-febbraio\/#primaryimage\"},\"datePublished\":\"2017-02-10T16:21:10+00:00\",\"dateModified\":\"2020-04-21T09:42:43+00:00\",\"author\":{\"@id\":\"https:\/\/www.botteroski.com\/blog\/#\/schema\/person\/2fc93067bf592038a7e9d5e3888ac01b\"},\"description\":\"Appuntamento sabato 18 febbraio per la Ciaspo-Polenta\\u2028: cena a base di polenta presso l'Apr\\u00e8s Ski Bottero Ski e ciaspolata notturna.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.botteroski.com\/blog\/2017\/02\/10\/ciaspo-polenta-unisciti-a-noi-la-sera-del-18-febbraio\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.botteroski.com\/blog\/2017\/02\/10\/ciaspo-polenta-unisciti-a-noi-la-sera-del-18-febbraio\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.botteroski.com\/blog\/2017\/02\/10\/ciaspo-polenta-unisciti-a-noi-la-sera-del-18-febbraio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Bottero Ski Blog\",\"item\":\"https:\/\/www.botteroski.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apr\\u00e8s Ski\",\"item\":\"https:\/\/www.botteroski.com\/blog\/apres-ski-2\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ciaspo-Polenta: unisciti a noi la sera del 18 febbraio\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.botteroski.com\/blog\/#\/schema\/person\/2fc93067bf592038a7e9d5e3888ac01b\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.botteroski.com\/blog\/#personlogo\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8a6fa094866616b6f09f982bcb295c0a?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8a6fa094866616b6f09f982bcb295c0a?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Redazione\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ciaspo-Polenta: unisciti a noi la sera del 18 febbraio - Bottero Ski Blog","description":"Appuntamento sabato 18 febbraio per la Ciaspo-Polenta\u2028: cena a base di polenta presso l'Apr\u00e8s Ski Bottero Ski e ciaspolata notturna.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.botteroski.com\/blog\/2017\/02\/10\/ciaspo-polenta-unisciti-a-noi-la-sera-del-18-febbraio\/","og_locale":"it_IT","og_type":"article","og_title":"Ciaspo-Polenta: unisciti a noi la sera del 18 febbraio - Bottero Ski Blog","og_description":"Appuntamento sabato 18 febbraio per la Ciaspo-Polenta\u2028: cena a base di polenta presso l'Apr\u00e8s Ski Bottero Ski e ciaspolata notturna.","og_url":"https:\/\/www.botteroski.com\/blog\/2017\/02\/10\/ciaspo-polenta-unisciti-a-noi-la-sera-del-18-febbraio\/","og_site_name":"Bottero Ski Blog","article_publisher":"https:\/\/www.facebook.com\/botteroski\/","article_published_time":"2017-02-10T16:21:10+00:00","article_modified_time":"2020-04-21T09:42:43+00:00","og_image":[{"width":1200,"height":1978,"url":"https:\/\/www.botteroski.com\/blog\/wp-content\/uploads\/2017\/02\/ciaspo-polenta-2107.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.botteroski.com\/blog\/#website","url":"https:\/\/www.botteroski.com\/blog\/","name":"Bottero Ski Blog","description":"News, curiosit\u00e0 e consigli dal mondo Botteroski!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.botteroski.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"ImageObject","@id":"https:\/\/www.botteroski.com\/blog\/2017\/02\/10\/ciaspo-polenta-unisciti-a-noi-la-sera-del-18-febbraio\/#primaryimage","inLanguage":"it-IT","url":"https:\/\/www.botteroski.com\/blog\/wp-content\/uploads\/2017\/02\/ciaspo-polenta-2107.jpg","contentUrl":"https:\/\/www.botteroski.com\/blog\/wp-content\/uploads\/2017\/02\/ciaspo-polenta-2107.jpg","width":1200,"height":1978},{"@type":"WebPage","@id":"https:\/\/www.botteroski.com\/blog\/2017\/02\/10\/ciaspo-polenta-unisciti-a-noi-la-sera-del-18-febbraio\/#webpage","url":"https:\/\/www.botteroski.com\/blog\/2017\/02\/10\/ciaspo-polenta-unisciti-a-noi-la-sera-del-18-febbraio\/","name":"Ciaspo-Polenta: unisciti a noi la sera del 18 febbraio - Bottero Ski Blog","isPartOf":{"@id":"https:\/\/www.botteroski.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.botteroski.com\/blog\/2017\/02\/10\/ciaspo-polenta-unisciti-a-noi-la-sera-del-18-febbraio\/#primaryimage"},"datePublished":"2017-02-10T16:21:10+00:00","dateModified":"2020-04-21T09:42:43+00:00","author":{"@id":"https:\/\/www.botteroski.com\/blog\/#\/schema\/person\/2fc93067bf592038a7e9d5e3888ac01b"},"description":"Appuntamento sabato 18 febbraio per la Ciaspo-Polenta\u2028: cena a base di polenta presso l'Apr\u00e8s Ski Bottero Ski e ciaspolata notturna.","breadcrumb":{"@id":"https:\/\/www.botteroski.com\/blog\/2017\/02\/10\/ciaspo-polenta-unisciti-a-noi-la-sera-del-18-febbraio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.botteroski.com\/blog\/2017\/02\/10\/ciaspo-polenta-unisciti-a-noi-la-sera-del-18-febbraio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.botteroski.com\/blog\/2017\/02\/10\/ciaspo-polenta-unisciti-a-noi-la-sera-del-18-febbraio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Bottero Ski Blog","item":"https:\/\/www.botteroski.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Apr\u00e8s Ski","item":"https:\/\/www.botteroski.com\/blog\/apres-ski-2\/"},{"@type":"ListItem","position":3,"name":"Ciaspo-Polenta: unisciti a noi la sera del 18 febbraio"}]},{"@type":"Person","@id":"https:\/\/www.botteroski.com\/blog\/#\/schema\/person\/2fc93067bf592038a7e9d5e3888ac01b","name":"Redazione","image":{"@type":"ImageObject","@id":"https:\/\/www.botteroski.com\/blog\/#personlogo","inLanguage":"it-IT","url":"https:\/\/secure.gravatar.com\/avatar\/8a6fa094866616b6f09f982bcb295c0a?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a6fa094866616b6f09f982bcb295c0a?s=96&d=wp_user_avatar&r=g","caption":"Redazione"}}]}},"_links":{"self":[{"href":"https:\/\/www.botteroski.com\/blog\/wp-json\/wp\/v2\/posts\/14158"}],"collection":[{"href":"https:\/\/www.botteroski.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.botteroski.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.botteroski.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.botteroski.com\/blog\/wp-json\/wp\/v2\/comments?post=14158"}],"version-history":[{"count":1,"href":"https:\/\/www.botteroski.com\/blog\/wp-json\/wp\/v2\/posts\/14158\/revisions"}],"predecessor-version":[{"id":21538,"href":"https:\/\/www.botteroski.com\/blog\/wp-json\/wp\/v2\/posts\/14158\/revisions\/21538"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.botteroski.com\/blog\/wp-json\/wp\/v2\/media\/14162"}],"wp:attachment":[{"href":"https:\/\/www.botteroski.com\/blog\/wp-json\/wp\/v2\/media?parent=14158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.botteroski.com\/blog\/wp-json\/wp\/v2\/categories?post=14158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.botteroski.com\/blog\/wp-json\/wp\/v2\/tags?post=14158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}