{"id":20723,"date":"2020-01-27T18:21:00","date_gmt":"2020-01-27T17:21:00","guid":{"rendered":"http:\/\/www.botteroskiblog.com\/?p=20723"},"modified":"2020-04-21T11:42:08","modified_gmt":"2020-04-21T09:42:08","slug":"sci-head-2021-disponibili-in-negozio-nuova-collezione","status":"publish","type":"post","link":"https:\/\/www.botteroski.com\/blog\/2020\/01\/27\/sci-head-2021-disponibili-in-negozio-nuova-collezione\/","title":{"rendered":"Sci Head 2021 disponibili in negozio!"},"content":{"rendered":"<h2><img class=\"aligncenter wp-image-20724 size-full\" src=\"https:\/\/www.botteroski.com\/blog\/wp-content\/uploads\/2020\/01\/Test-SCI-HEAD-2021-BannerSocial.jpg\" alt=\"sci head 2021 - i'm an image\" width=\"1200\" height=\"628\" srcset=\"https:\/\/www.botteroski.com\/blog\/wp-content\/uploads\/2020\/01\/Test-SCI-HEAD-2021-BannerSocial.jpg 1200w, https:\/\/www.botteroski.com\/blog\/wp-content\/uploads\/2020\/01\/Test-SCI-HEAD-2021-BannerSocial-300x157.jpg 300w, https:\/\/www.botteroski.com\/blog\/wp-content\/uploads\/2020\/01\/Test-SCI-HEAD-2021-BannerSocial-1024x536.jpg 1024w, https:\/\/www.botteroski.com\/blog\/wp-content\/uploads\/2020\/01\/Test-SCI-HEAD-2021-BannerSocial-768x402.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/h2>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_45 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\">Indice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" area-label=\"ez-toc-toggle-icon-1\"><label for=\"item-6a04fac410c55\" aria-label=\"Table of Content\"><span style=\"display: flex;align-items: center;width: 35px;height: 30px;justify-content: center;direction:ltr;\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/label><input  type=\"checkbox\" id=\"item-6a04fac410c55\"><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.botteroski.com\/blog\/2020\/01\/27\/sci-head-2021-disponibili-in-negozio-nuova-collezione\/#Sci_Head_2021_-_la_nuova_collezione_in_anteprima\" title=\"Sci Head 2021 &#8211; la nuova collezione in anteprima\">Sci Head 2021 &#8211; la nuova collezione in anteprima<\/a><ul class='ez-toc-list-level-6'><li class='ez-toc-heading-level-6'><ul class='ez-toc-list-level-6'><li class='ez-toc-heading-level-6'><ul class='ez-toc-list-level-6'><li class='ez-toc-heading-level-6'><ul class='ez-toc-list-level-6'><li class='ez-toc-heading-level-6'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.botteroski.com\/blog\/2020\/01\/27\/sci-head-2021-disponibili-in-negozio-nuova-collezione\/#Lasciati_stupire\" title=\"Lasciati stupire\">Lasciati stupire<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-6'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.botteroski.com\/blog\/2020\/01\/27\/sci-head-2021-disponibili-in-negozio-nuova-collezione\/#Scoprili_sul_nostro_sito_QUI\" title=\"Scoprili sul nostro sito QUI!\">Scoprili sul nostro sito QUI!<\/a><\/li><\/ul><\/li><\/ul><\/li><\/ul><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Sci_Head_2021_-_la_nuova_collezione_in_anteprima\"><\/span><span style=\"color: #ff0000;\"><strong>Sci Head 2021 &#8211; la nuova collezione in anteprima<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Vieni a trovarci nello store Bottero Ski di Limone oppure sul nostro sito e scopri la collezione sci Head 2021 in super anteprima<\/p>\n<h6><span class=\"ez-toc-section\" id=\"Lasciati_stupire\"><\/span><strong>Lasciati stupire<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h6>\n<p>Il nuovo Head Supershape prevede un aumento dell&#8217;angolo di inclinazione tra profilo esterno ed interno ed anima in legno alleggerita, con conseguente aumento significativo della stabilit\u00e0 e delle prestazioni.<br \/>\n<strong>La grande novit\u00e0 per\u00f2 \u00e8 il nuovissimo sistema EMC<\/strong> (Energy Management Circuit) che sostituisce la tecnologia KERS. Il sistema EMC, combinato con nuove tecnologie e materiali, regala ai nuovi sci Head morbidezza, facilit\u00e0 di utilizzo, migliore presa e adattabilit\u00e0 al terreno.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>Diversi sono i modelli disponibili, tutti a un prezzo speciale scontato del 20%!<\/strong><\/span><\/p>\n<h6><span class=\"ez-toc-section\" id=\"Scoprili_sul_nostro_sito_QUI\"><\/span><strong>Scoprili sul nostro sito <a href=\"https:\/\/www.botteroski.com\/it\/4_head\/s-9\/stagione-inverno_2021\">QUI!<\/a><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Sci Head 2021 &#8211; la nuova collezione in anteprima Vieni a trovarci nello store Bottero Ski di Limone oppure sul nostro sito e scopri la collezione sci Head 2021 in super anteprima Lasciati stupire Il nuovo Head Supershape prevede un aumento dell&#8217;angolo di inclinazione tra profilo esterno ed interno ed anima in legno alleggerita, con&#8230;<\/p>\n","protected":false},"author":2,"featured_media":20724,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6,13],"tags":[30,68,115,117,168,291,521,559],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sci Head 2021, la nuova collezione 2021 in anteprima! - Bottero Ski Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.botteroski.com\/blog\/2020\/01\/27\/sci-head-2021-disponibili-in-negozio-nuova-collezione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sci Head 2021, la nuova collezione 2021 in anteprima! - Bottero Ski Blog\" \/>\n<meta property=\"og:description\" content=\"Sci Head 2021 &#8211; la nuova collezione in anteprima Vieni a trovarci nello store Bottero Ski di Limone oppure sul nostro sito e scopri la collezione sci Head 2021 in super anteprima Lasciati stupire Il nuovo Head Supershape prevede un aumento dell&#8217;angolo di inclinazione tra profilo esterno ed interno ed anima in legno alleggerita, con...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.botteroski.com\/blog\/2020\/01\/27\/sci-head-2021-disponibili-in-negozio-nuova-collezione\/\" \/>\n<meta property=\"og:site_name\" content=\"Bottero Ski Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/botteroski\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-27T17:21:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-21T09:42:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.botteroski.com\/blog\/wp-content\/uploads\/2020\/01\/Test-SCI-HEAD-2021-BannerSocial.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.botteroski.com\/blog\/#website\",\"url\":\"https:\/\/www.botteroski.com\/blog\/\",\"name\":\"Bottero Ski Blog\",\"description\":\"News, curiosit\\u00e0 e consigli dal mondo Botteroski!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.botteroski.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.botteroski.com\/blog\/2020\/01\/27\/sci-head-2021-disponibili-in-negozio-nuova-collezione\/#primaryimage\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/www.botteroski.com\/blog\/wp-content\/uploads\/2020\/01\/Test-SCI-HEAD-2021-BannerSocial.jpg\",\"contentUrl\":\"https:\/\/www.botteroski.com\/blog\/wp-content\/uploads\/2020\/01\/Test-SCI-HEAD-2021-BannerSocial.jpg\",\"width\":1200,\"height\":628},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.botteroski.com\/blog\/2020\/01\/27\/sci-head-2021-disponibili-in-negozio-nuova-collezione\/#webpage\",\"url\":\"https:\/\/www.botteroski.com\/blog\/2020\/01\/27\/sci-head-2021-disponibili-in-negozio-nuova-collezione\/\",\"name\":\"Sci Head 2021, la nuova collezione 2021 in anteprima! - Bottero Ski Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.botteroski.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.botteroski.com\/blog\/2020\/01\/27\/sci-head-2021-disponibili-in-negozio-nuova-collezione\/#primaryimage\"},\"datePublished\":\"2020-01-27T17:21:00+00:00\",\"dateModified\":\"2020-04-21T09:42:08+00:00\",\"author\":{\"@id\":\"https:\/\/www.botteroski.com\/blog\/#\/schema\/person\/2fc93067bf592038a7e9d5e3888ac01b\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.botteroski.com\/blog\/2020\/01\/27\/sci-head-2021-disponibili-in-negozio-nuova-collezione\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.botteroski.com\/blog\/2020\/01\/27\/sci-head-2021-disponibili-in-negozio-nuova-collezione\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.botteroski.com\/blog\/2020\/01\/27\/sci-head-2021-disponibili-in-negozio-nuova-collezione\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Bottero Ski Blog\",\"item\":\"https:\/\/www.botteroski.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BotteroSkiCup\",\"item\":\"https:\/\/www.botteroski.com\/blog\/botteroskicup\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sci Head 2021 disponibili in negozio!\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.botteroski.com\/blog\/#\/schema\/person\/2fc93067bf592038a7e9d5e3888ac01b\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.botteroski.com\/blog\/#personlogo\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8a6fa094866616b6f09f982bcb295c0a?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8a6fa094866616b6f09f982bcb295c0a?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Redazione\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sci Head 2021, la nuova collezione 2021 in anteprima! - Bottero Ski Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.botteroski.com\/blog\/2020\/01\/27\/sci-head-2021-disponibili-in-negozio-nuova-collezione\/","og_locale":"it_IT","og_type":"article","og_title":"Sci Head 2021, la nuova collezione 2021 in anteprima! - Bottero Ski Blog","og_description":"Sci Head 2021 &#8211; la nuova collezione in anteprima Vieni a trovarci nello store Bottero Ski di Limone oppure sul nostro sito e scopri la collezione sci Head 2021 in super anteprima Lasciati stupire Il nuovo Head Supershape prevede un aumento dell&#8217;angolo di inclinazione tra profilo esterno ed interno ed anima in legno alleggerita, con...","og_url":"https:\/\/www.botteroski.com\/blog\/2020\/01\/27\/sci-head-2021-disponibili-in-negozio-nuova-collezione\/","og_site_name":"Bottero Ski Blog","article_publisher":"https:\/\/www.facebook.com\/botteroski\/","article_published_time":"2020-01-27T17:21:00+00:00","article_modified_time":"2020-04-21T09:42:08+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.botteroski.com\/blog\/wp-content\/uploads\/2020\/01\/Test-SCI-HEAD-2021-BannerSocial.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.botteroski.com\/blog\/#website","url":"https:\/\/www.botteroski.com\/blog\/","name":"Bottero Ski Blog","description":"News, curiosit\u00e0 e consigli dal mondo Botteroski!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.botteroski.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"ImageObject","@id":"https:\/\/www.botteroski.com\/blog\/2020\/01\/27\/sci-head-2021-disponibili-in-negozio-nuova-collezione\/#primaryimage","inLanguage":"it-IT","url":"https:\/\/www.botteroski.com\/blog\/wp-content\/uploads\/2020\/01\/Test-SCI-HEAD-2021-BannerSocial.jpg","contentUrl":"https:\/\/www.botteroski.com\/blog\/wp-content\/uploads\/2020\/01\/Test-SCI-HEAD-2021-BannerSocial.jpg","width":1200,"height":628},{"@type":"WebPage","@id":"https:\/\/www.botteroski.com\/blog\/2020\/01\/27\/sci-head-2021-disponibili-in-negozio-nuova-collezione\/#webpage","url":"https:\/\/www.botteroski.com\/blog\/2020\/01\/27\/sci-head-2021-disponibili-in-negozio-nuova-collezione\/","name":"Sci Head 2021, la nuova collezione 2021 in anteprima! - Bottero Ski Blog","isPartOf":{"@id":"https:\/\/www.botteroski.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.botteroski.com\/blog\/2020\/01\/27\/sci-head-2021-disponibili-in-negozio-nuova-collezione\/#primaryimage"},"datePublished":"2020-01-27T17:21:00+00:00","dateModified":"2020-04-21T09:42:08+00:00","author":{"@id":"https:\/\/www.botteroski.com\/blog\/#\/schema\/person\/2fc93067bf592038a7e9d5e3888ac01b"},"breadcrumb":{"@id":"https:\/\/www.botteroski.com\/blog\/2020\/01\/27\/sci-head-2021-disponibili-in-negozio-nuova-collezione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.botteroski.com\/blog\/2020\/01\/27\/sci-head-2021-disponibili-in-negozio-nuova-collezione\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.botteroski.com\/blog\/2020\/01\/27\/sci-head-2021-disponibili-in-negozio-nuova-collezione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Bottero Ski Blog","item":"https:\/\/www.botteroski.com\/blog\/"},{"@type":"ListItem","position":2,"name":"BotteroSkiCup","item":"https:\/\/www.botteroski.com\/blog\/botteroskicup\/"},{"@type":"ListItem","position":3,"name":"Sci Head 2021 disponibili in negozio!"}]},{"@type":"Person","@id":"https:\/\/www.botteroski.com\/blog\/#\/schema\/person\/2fc93067bf592038a7e9d5e3888ac01b","name":"Redazione","image":{"@type":"ImageObject","@id":"https:\/\/www.botteroski.com\/blog\/#personlogo","inLanguage":"it-IT","url":"https:\/\/secure.gravatar.com\/avatar\/8a6fa094866616b6f09f982bcb295c0a?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a6fa094866616b6f09f982bcb295c0a?s=96&d=wp_user_avatar&r=g","caption":"Redazione"}}]}},"_links":{"self":[{"href":"https:\/\/www.botteroski.com\/blog\/wp-json\/wp\/v2\/posts\/20723"}],"collection":[{"href":"https:\/\/www.botteroski.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.botteroski.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.botteroski.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.botteroski.com\/blog\/wp-json\/wp\/v2\/comments?post=20723"}],"version-history":[{"count":1,"href":"https:\/\/www.botteroski.com\/blog\/wp-json\/wp\/v2\/posts\/20723\/revisions"}],"predecessor-version":[{"id":21185,"href":"https:\/\/www.botteroski.com\/blog\/wp-json\/wp\/v2\/posts\/20723\/revisions\/21185"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.botteroski.com\/blog\/wp-json\/wp\/v2\/media\/20724"}],"wp:attachment":[{"href":"https:\/\/www.botteroski.com\/blog\/wp-json\/wp\/v2\/media?parent=20723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.botteroski.com\/blog\/wp-json\/wp\/v2\/categories?post=20723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.botteroski.com\/blog\/wp-json\/wp\/v2\/tags?post=20723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}