{"id":419,"count":1,"description":"","link":"https:\/\/www.botteroski.com\/blog\/tag\/offerta-speciale\/","name":"offerta speciale","slug":"offerta-speciale","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>offerta speciale Archivi - Bottero Ski Blog<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"offerta speciale Archivi - Bottero Ski Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.botteroski.com\/blog\/tag\/offerta-speciale\/\" \/>\n<meta property=\"og:site_name\" content=\"Bottero Ski Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.botteroski.com\/blog\/#website\",\"url\":\"https:\/\/www.botteroski.com\/blog\/\",\"name\":\"Bottero Ski Blog\",\"description\":\"News, curiosit\\u00e0 e consigli dal mondo Botteroski!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.botteroski.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.botteroski.com\/blog\/tag\/offerta-speciale\/#webpage\",\"url\":\"https:\/\/www.botteroski.com\/blog\/tag\/offerta-speciale\/\",\"name\":\"offerta speciale Archivi - Bottero Ski Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.botteroski.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.botteroski.com\/blog\/tag\/offerta-speciale\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.botteroski.com\/blog\/tag\/offerta-speciale\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.botteroski.com\/blog\/tag\/offerta-speciale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Bottero Ski Blog\",\"item\":\"https:\/\/www.botteroski.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"offerta speciale\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"offerta speciale Archivi - Bottero Ski Blog","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"offerta speciale Archivi - Bottero Ski Blog","og_url":"https:\/\/www.botteroski.com\/blog\/tag\/offerta-speciale\/","og_site_name":"Bottero Ski Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.botteroski.com\/blog\/#website","url":"https:\/\/www.botteroski.com\/blog\/","name":"Bottero Ski Blog","description":"News, curiosit\u00e0 e consigli dal mondo Botteroski!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.botteroski.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"CollectionPage","@id":"https:\/\/www.botteroski.com\/blog\/tag\/offerta-speciale\/#webpage","url":"https:\/\/www.botteroski.com\/blog\/tag\/offerta-speciale\/","name":"offerta speciale Archivi - Bottero Ski Blog","isPartOf":{"@id":"https:\/\/www.botteroski.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.botteroski.com\/blog\/tag\/offerta-speciale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.botteroski.com\/blog\/tag\/offerta-speciale\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.botteroski.com\/blog\/tag\/offerta-speciale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Bottero Ski Blog","item":"https:\/\/www.botteroski.com\/blog\/"},{"@type":"ListItem","position":2,"name":"offerta speciale"}]}]}},"_links":{"self":[{"href":"https:\/\/www.botteroski.com\/blog\/wp-json\/wp\/v2\/tags\/419"}],"collection":[{"href":"https:\/\/www.botteroski.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.botteroski.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.botteroski.com\/blog\/wp-json\/wp\/v2\/posts?tags=419"},{"href":"https:\/\/www.botteroski.com\/blog\/wp-json\/wp\/v2\/pmb_content?tags=419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}